{"id":38,"date":"2021-12-08T11:38:53","date_gmt":"2021-12-08T11:38:53","guid":{"rendered":"https:\/\/kadence.pixel-show.com\/outdoor-shop\/?page_id=13"},"modified":"2023-12-06T23:11:38","modified_gmt":"2023-12-06T22:11:38","slug":"home","status":"publish","type":"page","link":"https:\/\/vetihcr.com\/","title":{"rendered":"Home"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"38\" class=\"elementor elementor-38\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4aaf1b8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4aaf1b8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2b7f38c\" data-id=\"2b7f38c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-85b4501 elementor-widget elementor-widget-heading\" data-id=\"85b4501\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.18.0 - 06-12-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-default\">V\u00eatements h\u00f4tel, caf\u00e9, restaurant<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cc6e583 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cc6e583\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cfb82b9\" data-id=\"cfb82b9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b16b8e elementor-widget elementor-widget-text-editor\" data-id=\"1b16b8e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.18.0 - 06-12-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Trouvez sur notre site tous les v\u00eatements et \u00e9quipements n\u00e9cessaires dans les m\u00e9tiers de la restauration et du service.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7209e2e\" data-id=\"7209e2e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7e78af elementor-align-left elementor-tablet-align-center elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"e7e78af\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Je d\u00e9couvre<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e295407\" data-id=\"e295407\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4f05c4d elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4f05c4d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-272997c\" data-id=\"272997c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7544683\" data-id=\"7544683\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8cd869b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8cd869b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-a0363ac\" data-id=\"a0363ac\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9191215 elementor-widget elementor-widget-image\" data-id=\"9191215\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.18.0 - 06-12-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-tim-douglas-6205756-1024x683.jpg\" class=\"attachment-large size-large wp-image-1208\" alt=\"\" srcset=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-tim-douglas-6205756-1024x683.jpg 1024w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-tim-douglas-6205756-300x200.jpg 300w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-tim-douglas-6205756-768x512.jpg 768w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-tim-douglas-6205756-1536x1024.jpg 1536w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-tim-douglas-6205756-2048x1365.jpg 2048w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-tim-douglas-6205756-600x400.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68ae8b2 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"68ae8b2\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Caf\u00e9<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-619bce6\" data-id=\"619bce6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa597cb elementor-widget elementor-widget-image\" data-id=\"aa597cb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-elle-hughes-2696064-1024x683.jpg\" class=\"attachment-large size-large wp-image-504\" alt=\"\" srcset=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-elle-hughes-2696064-1024x683.jpg 1024w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-elle-hughes-2696064-300x200.jpg 300w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-elle-hughes-2696064-768x512.jpg 768w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-elle-hughes-2696064-1536x1024.jpg 1536w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-elle-hughes-2696064-2048x1365.jpg 2048w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-elle-hughes-2696064-600x400.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e6dc626 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"e6dc626\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Restaurant<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-bfd0f43\" data-id=\"bfd0f43\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d15065e elementor-widget elementor-widget-image\" data-id=\"d15065e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-cottonbro-studio-6466496-1024x683.jpg\" class=\"attachment-large size-large wp-image-1214\" alt=\"\" srcset=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-cottonbro-studio-6466496-1024x683.jpg 1024w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-cottonbro-studio-6466496-300x200.jpg 300w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-cottonbro-studio-6466496-768x512.jpg 768w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-cottonbro-studio-6466496-1536x1024.jpg 1536w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-cottonbro-studio-6466496-2048x1365.jpg 2048w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-cottonbro-studio-6466496-600x400.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77a57f2 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"77a57f2\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">H\u00f4tel<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-86a2562 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"86a2562\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d44ae1\" data-id=\"7d44ae1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db2e224 elementor-widget elementor-widget-image-carousel\" data-id=\"db2e224\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;7&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:80,&quot;sizes&quot;:[]},&quot;slides_to_show_tablet&quot;:&quot;3&quot;,&quot;slides_to_show_mobile&quot;:&quot;2&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.18.0 - 06-12-2023 *\/\n.elementor-widget-image-carousel .swiper,.elementor-widget-image-carousel .swiper-container{position:static}.elementor-widget-image-carousel .swiper-container .swiper-slide figure,.elementor-widget-image-carousel .swiper .swiper-slide figure{line-height:inherit}.elementor-widget-image-carousel .swiper-slide{text-align:center}.elementor-image-carousel-wrapper:not(.swiper-container-initialized):not(.swiper-initialized) .swiper-slide{max-width:calc(100% \/ var(--e-image-carousel-slides-to-show, 3))}<\/style>\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/3-small_default.png\" alt=\"3-small_default\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/5-small_default.jpg\" alt=\"5-small_default\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/6-small_default.jpg\" alt=\"6-small_default\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/7-small_default.jpg\" alt=\"7-small_default\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/9-small_default.jpg\" alt=\"9-small_default\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/10-small_default.png\" alt=\"10-small_default\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/11-small_default.jpg\" alt=\"11-small_default\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/12-small_default.jpg\" alt=\"12-small_default\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/13-small_default.jpg\" alt=\"13-small_default\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/14-small_default.png\" alt=\"14-small_default\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 of 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/15-small_default.jpg\" alt=\"15-small_default\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 of 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/16-small_default.jpg\" alt=\"16-small_default\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 of 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/18-small_default.jpg\" alt=\"18-small_default\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 of 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/19-small_default.jpg\" alt=\"19-small_default\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 of 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/20-small_default-1.jpg\" alt=\"20-small_default (1)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"16 of 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/21-small_default.png\" alt=\"21-small_default\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"17 of 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/24-small_default.jpg\" alt=\"24-small_default\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"18 of 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/26-small_default.jpg\" alt=\"26-small_default\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"19 of 19\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/27-small_default.png\" alt=\"27-small_default\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-97cb353 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"97cb353\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6344f74\" data-id=\"6344f74\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7557baf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7557baf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7219301\" data-id=\"7219301\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bbdcbb7 elementor-widget elementor-widget-heading\" data-id=\"bbdcbb7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Notre best-seller<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43f4511 elementor-widget elementor-widget-text-editor\" data-id=\"43f4511\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-97d988c elementor-widget elementor-widget-image\" data-id=\"97d988c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"1000\" src=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/Purple-Futuristic-Web-Agreement-Banner-873-\u00d7-460-px-1500-x-1000-px-1.png\" class=\"attachment-full size-full wp-image-1287\" alt=\"\" srcset=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/Purple-Futuristic-Web-Agreement-Banner-873-\u00d7-460-px-1500-x-1000-px-1.png 1500w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/Purple-Futuristic-Web-Agreement-Banner-873-\u00d7-460-px-1500-x-1000-px-1-300x200.png 300w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/Purple-Futuristic-Web-Agreement-Banner-873-\u00d7-460-px-1500-x-1000-px-1-1024x683.png 1024w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/Purple-Futuristic-Web-Agreement-Banner-873-\u00d7-460-px-1500-x-1000-px-1-768x512.png 768w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/Purple-Futuristic-Web-Agreement-Banner-873-\u00d7-460-px-1500-x-1000-px-1-600x400.png 600w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8aa8736 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8aa8736\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-81c187d\" data-id=\"81c187d\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4cd0fea elementor-star-rating-tablet--align-center elementor--star-style-star_fontawesome elementor-widget elementor-widget-star-rating\" data-id=\"4cd0fea\" data-element_type=\"widget\" data-widget_type=\"star-rating.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.18.0 - 06-12-2023 *\/\n@charset \"UTF-8\";.elementor-star-rating{color:#ccd6df;font-family:eicons;display:inline-block}.elementor-star-rating i{display:inline-block;position:relative;font-style:normal;cursor:default}.elementor-star-rating i:before{content:\"\\e934\";display:block;font-size:inherit;font-family:inherit;position:absolute;overflow:hidden;color:#f0ad4e;top:0;left:0}.elementor-star-rating .elementor-star-empty:before{content:none}.elementor-star-rating .elementor-star-1:before{width:10%}.elementor-star-rating .elementor-star-2:before{width:20%}.elementor-star-rating .elementor-star-3:before{width:30%}.elementor-star-rating .elementor-star-4:before{width:40%}.elementor-star-rating .elementor-star-5:before{width:50%}.elementor-star-rating .elementor-star-6:before{width:60%}.elementor-star-rating .elementor-star-7:before{width:70%}.elementor-star-rating .elementor-star-8:before{width:80%}.elementor-star-rating .elementor-star-9:before{width:90%}.elementor-star-rating__wrapper{display:flex;align-items:center}.elementor-star-rating__title{margin-right:10px}.elementor-star-rating--align-right .elementor-star-rating__wrapper{text-align:right;justify-content:flex-end}.elementor-star-rating--align-left .elementor-star-rating__wrapper{text-align:left;justify-content:flex-start}.elementor-star-rating--align-center .elementor-star-rating__wrapper{text-align:center;justify-content:center}.elementor-star-rating--align-justify .elementor-star-rating__title{margin-right:auto}@media (max-width:1024px){.elementor-star-rating-tablet--align-right .elementor-star-rating__wrapper{text-align:right;justify-content:flex-end}.elementor-star-rating-tablet--align-left .elementor-star-rating__wrapper{text-align:left;justify-content:flex-start}.elementor-star-rating-tablet--align-center .elementor-star-rating__wrapper{text-align:center;justify-content:center}.elementor-star-rating-tablet--align-justify .elementor-star-rating__title{margin-right:auto}}@media (max-width:767px){.elementor-star-rating-mobile--align-right .elementor-star-rating__wrapper{text-align:right;justify-content:flex-end}.elementor-star-rating-mobile--align-left .elementor-star-rating__wrapper{text-align:left;justify-content:flex-start}.elementor-star-rating-mobile--align-center .elementor-star-rating__wrapper{text-align:center;justify-content:center}.elementor-star-rating-mobile--align-justify .elementor-star-rating__title{margin-right:auto}}.last-star{letter-spacing:0}.elementor--star-style-star_unicode .elementor-star-rating{font-family:Arial,Helvetica,sans-serif}.elementor--star-style-star_unicode .elementor-star-rating i:not(.elementor-star-empty):before{content:\"\u2605\"}<\/style>\n\t\t<div class=\"elementor-star-rating__wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-star-rating\" title=\"5\/5\" itemtype=\"http:\/\/schema.org\/Rating\" itemscope=\"\" itemprop=\"reviewRating\"><i class=\"elementor-star-full\">&#xE934;<\/i><i class=\"elementor-star-full\">&#xE934;<\/i><i class=\"elementor-star-full\">&#xE934;<\/i><i class=\"elementor-star-full\">&#xE934;<\/i><i class=\"elementor-star-full\">&#xE934;<\/i> <span itemprop=\"ratingValue\" class=\"elementor-screen-only\">5\/5<\/span><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2fe8b3 elementor-widget elementor-widget-heading\" data-id=\"f2fe8b3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">VESTE DE CUISINE A\u00c9R\u00c9E NOIR - MANCHE LONGUE - PORTWEST<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-02466e4 elementor-widget elementor-widget-text-editor\" data-id=\"02466e4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>a veste de cuisine Portwest C838\u00a0utilise un tissu l\u00e9ger et de grands panneaux MeshAir Pro \u00e0 l&#8217;arri\u00e8re et aux aisselles pour une respirabilit\u00e9 exceptionnelle. Dot\u00e9 d&#8217;une fermeture \u00e0 double boutonnage sur le devant et d&#8217;une patte pour tablier \u00e0 l&#8217;arri\u00e8re du cou,\u00a0 cette veste de cuisine sera votre alli\u00e9 en associant l\u00e9g\u00e8ret\u00e9, confort et style.\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a3b7177 elementor-widget elementor-widget-heading\" data-id=\"a3b7177\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">36,00 \u20ac TTC<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bcf9436\" data-id=\"bcf9436\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f3b6c1d elementor-absolute elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-path\" data-id=\"f3b6c1d\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;link&quot;:{&quot;url&quot;:&quot;&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;start_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]}}\" data-widget_type=\"text-path.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"e-text-path\" data-text=\"\" data-url=\"\/\/vetihcr.com\/wp-content\/plugins\/elementor\/assets\/svg-paths\/line.svg\" data-link-url=\"\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-714b0c9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"714b0c9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-148b744\" data-id=\"148b744\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a80332 elementor-widget elementor-widget-image\" data-id=\"2a80332\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"1000\" src=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/Purple-Futuristic-Web-Agreement-Banner-873-\u00d7-460-px-1500-x-1000-px-2.png\" class=\"attachment-full size-full wp-image-1291\" alt=\"\" srcset=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/Purple-Futuristic-Web-Agreement-Banner-873-\u00d7-460-px-1500-x-1000-px-2.png 1500w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/Purple-Futuristic-Web-Agreement-Banner-873-\u00d7-460-px-1500-x-1000-px-2-300x200.png 300w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/Purple-Futuristic-Web-Agreement-Banner-873-\u00d7-460-px-1500-x-1000-px-2-1024x683.png 1024w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/Purple-Futuristic-Web-Agreement-Banner-873-\u00d7-460-px-1500-x-1000-px-2-768x512.png 768w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/Purple-Futuristic-Web-Agreement-Banner-873-\u00d7-460-px-1500-x-1000-px-2-600x400.png 600w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e43a83b elementor-star-rating-tablet--align-center elementor--star-style-star_fontawesome elementor-widget elementor-widget-star-rating\" data-id=\"e43a83b\" data-element_type=\"widget\" data-widget_type=\"star-rating.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div class=\"elementor-star-rating__wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-star-rating\" title=\"5\/5\" itemtype=\"http:\/\/schema.org\/Rating\" itemscope=\"\" itemprop=\"reviewRating\"><i class=\"elementor-star-full\">&#xE934;<\/i><i class=\"elementor-star-full\">&#xE934;<\/i><i class=\"elementor-star-full\">&#xE934;<\/i><i class=\"elementor-star-full\">&#xE934;<\/i><i class=\"elementor-star-full\">&#xE934;<\/i> <span itemprop=\"ratingValue\" class=\"elementor-screen-only\">5\/5<\/span><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-180e605 elementor-widget elementor-widget-heading\" data-id=\"180e605\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">PANTALON DE CUISINE MESHAIR PRO NOIR - RESPIRANT, D\u00c9PERLANT ET CONFORTABLE<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bcd2833 elementor-widget elementor-widget-heading\" data-id=\"bcd2833\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">30,00 \u20ac TTC<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-240bce8\" data-id=\"240bce8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-91eae1c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"91eae1c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f3e94a0\" data-id=\"f3e94a0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f7fd17 elementor-widget elementor-widget-image\" data-id=\"0f7fd17\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"1000\" src=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/Purple-Futuristic-Web-Agreement-Banner-873-\u00d7-460-px-1500-x-1000-px-9.png\" class=\"attachment-1536x1536 size-1536x1536 wp-image-1307\" alt=\"\" srcset=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/Purple-Futuristic-Web-Agreement-Banner-873-\u00d7-460-px-1500-x-1000-px-9.png 1500w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/Purple-Futuristic-Web-Agreement-Banner-873-\u00d7-460-px-1500-x-1000-px-9-300x200.png 300w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/Purple-Futuristic-Web-Agreement-Banner-873-\u00d7-460-px-1500-x-1000-px-9-1024x683.png 1024w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/Purple-Futuristic-Web-Agreement-Banner-873-\u00d7-460-px-1500-x-1000-px-9-768x512.png 768w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/Purple-Futuristic-Web-Agreement-Banner-873-\u00d7-460-px-1500-x-1000-px-9-600x400.png 600w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-face90e\" data-id=\"face90e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bb2f863 elementor-star-rating-mobile--align-center elementor--star-style-star_fontawesome elementor-widget elementor-widget-star-rating\" data-id=\"bb2f863\" data-element_type=\"widget\" data-widget_type=\"star-rating.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div class=\"elementor-star-rating__wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-star-rating\" title=\"5\/5\" itemtype=\"http:\/\/schema.org\/Rating\" itemscope=\"\" itemprop=\"reviewRating\"><i class=\"elementor-star-full\">&#xE934;<\/i><i class=\"elementor-star-full\">&#xE934;<\/i><i class=\"elementor-star-full\">&#xE934;<\/i><i class=\"elementor-star-full\">&#xE934;<\/i><i class=\"elementor-star-full\">&#xE934;<\/i> <span itemprop=\"ratingValue\" class=\"elementor-screen-only\">5\/5<\/span><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5281d33 elementor-widget elementor-widget-heading\" data-id=\"5281d33\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">ESCARPIN DE TRAVAIL FEMME EN CUIR LESCAL<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-569c82f elementor-widget elementor-widget-text-editor\" data-id=\"569c82f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span id=\"p0\"><span class=\"s-rg-t\">Lescal<\/span>\u00a0est une chaussure de travail \u00e0 talon tout en cuir, int\u00e9rieur comme ext\u00e9rieur.<\/span><span id=\"p7\">\u00a0 <strong>Fabrication fran\u00e7aise<\/strong><\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14e3b4b elementor-widget elementor-widget-heading\" data-id=\"14e3b4b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">$64<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9c316a6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9c316a6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3517b62\" data-id=\"3517b62\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-653ccf9 elementor-widget elementor-widget-image\" data-id=\"653ccf9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/Purple-Futuristic-Web-Agreement-Banner-873-\u00d7-460-px-1500-x-1000-px-5-1024x683.png\" class=\"attachment-large size-large wp-image-1300\" alt=\"\" srcset=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/Purple-Futuristic-Web-Agreement-Banner-873-\u00d7-460-px-1500-x-1000-px-5-1024x683.png 1024w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/Purple-Futuristic-Web-Agreement-Banner-873-\u00d7-460-px-1500-x-1000-px-5-300x200.png 300w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/Purple-Futuristic-Web-Agreement-Banner-873-\u00d7-460-px-1500-x-1000-px-5-768x512.png 768w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/Purple-Futuristic-Web-Agreement-Banner-873-\u00d7-460-px-1500-x-1000-px-5-600x400.png 600w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/12\/Purple-Futuristic-Web-Agreement-Banner-873-\u00d7-460-px-1500-x-1000-px-5.png 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24d6cf1 elementor-absolute elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-path\" data-id=\"24d6cf1\" data-element_type=\"widget\" data-settings=\"{&quot;text&quot;:&quot;Derni\\u00e8res paires disponibles&quot;,&quot;_position&quot;:&quot;absolute&quot;,&quot;link&quot;:{&quot;url&quot;:&quot;&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;start_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]}}\" data-widget_type=\"text-path.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"e-text-path\" data-text=\"Derni&egrave;res paires disponibles\" data-url=\"\/\/vetihcr.com\/wp-content\/plugins\/elementor\/assets\/svg-paths\/line.svg\" data-link-url=\"\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8fcae3b\" data-id=\"8fcae3b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e373420 elementor-star-rating-mobile--align-center elementor--star-style-star_fontawesome elementor-widget elementor-widget-star-rating\" data-id=\"e373420\" data-element_type=\"widget\" data-widget_type=\"star-rating.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div class=\"elementor-star-rating__wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-star-rating\" title=\"5\/5\" itemtype=\"http:\/\/schema.org\/Rating\" itemscope=\"\" itemprop=\"reviewRating\"><i class=\"elementor-star-full\">&#xE934;<\/i><i class=\"elementor-star-full\">&#xE934;<\/i><i class=\"elementor-star-full\">&#xE934;<\/i><i class=\"elementor-star-full\">&#xE934;<\/i><i class=\"elementor-star-full\">&#xE934;<\/i> <span itemprop=\"ratingValue\" class=\"elementor-screen-only\">5\/5<\/span><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c55afeb elementor-widget elementor-widget-heading\" data-id=\"c55afeb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">CHAUSSURES DE S\u00c9CURIT\u00c9 Joko <\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f732c58 elementor-widget elementor-widget-text-editor\" data-id=\"f732c58\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Chaussure de s\u00e9curit\u00e9 agro alimentaire Joko Blanc avec vo\u00fbte plantaire suspendue S2 SRC<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-103b0a6 elementor-widget elementor-widget-heading\" data-id=\"103b0a6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">79,00 \u20ac TTC<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b885125 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b885125\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e1362ae\" data-id=\"e1362ae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-268fb0f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"268fb0f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b023837\" data-id=\"b023837\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f4b9d0d elementor-widget elementor-widget-heading\" data-id=\"f4b9d0d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Nouvelle collection<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84e7158 elementor-widget elementor-widget-heading\" data-id=\"84e7158\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Explorez nos cat\u00e9gories<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b9e921 elementor-widget elementor-widget-text-editor\" data-id=\"7b9e921\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2b36a3d\" data-id=\"2b36a3d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1147969 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1147969\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-52959ff\" data-id=\"52959ff\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a57b29 elementor-widget elementor-widget-image\" data-id=\"8a57b29\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2500\" height=\"1663\" src=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-aljona-ovtsinnikova-18601970.jpg\" class=\"attachment-full size-full wp-image-1233\" alt=\"\" srcset=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-aljona-ovtsinnikova-18601970.jpg 2500w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-aljona-ovtsinnikova-18601970-300x200.jpg 300w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-aljona-ovtsinnikova-18601970-1024x681.jpg 1024w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-aljona-ovtsinnikova-18601970-768x511.jpg 768w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-aljona-ovtsinnikova-18601970-1536x1022.jpg 1536w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-aljona-ovtsinnikova-18601970-2048x1362.jpg 2048w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-aljona-ovtsinnikova-18601970-600x399.jpg 600w\" sizes=\"(max-width: 2500px) 100vw, 2500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-060eddb elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"060eddb\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/vetihcr.com\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-box.min.css\">\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\tChaussures\t\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9666ab elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"e9666ab\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">D\u00e9couvrir<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b989457\" data-id=\"b989457\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b7be72d elementor-widget elementor-widget-image\" data-id=\"b7be72d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-tanya-gorelova-3933219-scaled.jpg\" class=\"attachment-full size-full wp-image-1231\" alt=\"\" srcset=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-tanya-gorelova-3933219-scaled.jpg 2560w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-tanya-gorelova-3933219-300x200.jpg 300w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-tanya-gorelova-3933219-1024x683.jpg 1024w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-tanya-gorelova-3933219-768x512.jpg 768w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-tanya-gorelova-3933219-1536x1024.jpg 1536w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-tanya-gorelova-3933219-2048x1365.jpg 2048w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-tanya-gorelova-3933219-600x400.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e12e89f elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"e12e89f\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\tGants\t\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb5034d elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"fb5034d\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">D\u00e9couvrir<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-723710f\" data-id=\"723710f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c2f8e8e elementor-widget elementor-widget-image\" data-id=\"c2f8e8e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-rene-asmussen-3217157-scaled.jpg\" class=\"attachment-full size-full wp-image-1230\" alt=\"\" srcset=\"https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-rene-asmussen-3217157-scaled.jpg 2560w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-rene-asmussen-3217157-300x200.jpg 300w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-rene-asmussen-3217157-1024x683.jpg 1024w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-rene-asmussen-3217157-768x512.jpg 768w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-rene-asmussen-3217157-1536x1024.jpg 1536w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-rene-asmussen-3217157-2048x1365.jpg 2048w, https:\/\/vetihcr.com\/wp-content\/uploads\/2023\/11\/pexels-rene-asmussen-3217157-600x400.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae084e7 elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"ae084e7\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\tUniformes\t\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd3ffee elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"dd3ffee\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">D\u00e9couvrir<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-99cb033 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"99cb033\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8a26424\" data-id=\"8a26424\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b7f6f20 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b7f6f20\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3429877\" data-id=\"3429877\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d7305ae elementor-widget elementor-widget-heading\" data-id=\"d7305ae\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nos meilleures ventes<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28b2d2d elementor-widget elementor-widget-text-editor\" data-id=\"28b2d2d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c0fee5 elementor-widget elementor-widget-shortcode\" data-id=\"3c0fee5\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"woocommerce columns-4 \"><ul class=\"products content-wrap product-archive grid-cols grid-ss-col-2 grid-sm-col-3 grid-lg-col-4 woo-archive-action-on-hover woo-archive-btn-text  woo-archive-image-hover-none\"><li class=\"entry content-bg loop-entry product type-product post-523 status-publish first instock product_cat-shelters has-post-thumbnail shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/vetihcr.com\/index.php\/product\/altaplex-tarp-w-doors\/\" class=\"woocommerce-loop-image-link woocommerce-LoopProduct-link woocommerce-loop-product__link\"><\/a><div class=\"product-details content-bg entry-content-wrap\"><h2 class=\"woocommerce-loop-product__title\"><a href=\"https:\/\/vetihcr.com\/index.php\/product\/altaplex-tarp-w-doors\/\" class=\"woocommerce-LoopProduct-link-title woocommerce-loop-product__title_ink\">Altaplex Tarp w\/ Doors<\/a><\/h2><div class=\"product-action-wrap\"><\/div><\/div><\/li>\n<li class=\"entry content-bg loop-entry product type-product post-516 status-publish instock product_cat-backpacks has-post-thumbnail shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/vetihcr.com\/index.php\/product\/arc-air-zip-62l\/\" class=\"woocommerce-loop-image-link woocommerce-LoopProduct-link woocommerce-loop-product__link\"><\/a><div class=\"product-details content-bg entry-content-wrap\"><h2 class=\"woocommerce-loop-product__title\"><a href=\"https:\/\/vetihcr.com\/index.php\/product\/arc-air-zip-62l\/\" class=\"woocommerce-LoopProduct-link-title woocommerce-loop-product__title_ink\">Arc Air Zip 62L<\/a><\/h2><div class=\"product-action-wrap\"><\/div><\/div><\/li>\n<li class=\"entry content-bg loop-entry product type-product post-517 status-publish instock product_cat-backpacks has-post-thumbnail shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/vetihcr.com\/index.php\/product\/arc-blast-55l\/\" class=\"woocommerce-loop-image-link woocommerce-LoopProduct-link woocommerce-loop-product__link\"><\/a><div class=\"product-details content-bg entry-content-wrap\"><h2 class=\"woocommerce-loop-product__title\"><a href=\"https:\/\/vetihcr.com\/index.php\/product\/arc-blast-55l\/\" class=\"woocommerce-LoopProduct-link-title woocommerce-loop-product__title_ink\">Arc Blast 55L<\/a><\/h2><div class=\"product-action-wrap\"><\/div><\/div><\/li>\n<li class=\"entry content-bg loop-entry product type-product post-524 status-publish last instock product_cat-backpacks has-post-thumbnail shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/vetihcr.com\/index.php\/product\/bagger-25l-backpack\/\" class=\"woocommerce-loop-image-link woocommerce-LoopProduct-link woocommerce-loop-product__link\"><\/a><div class=\"product-details content-bg entry-content-wrap\"><h2 class=\"woocommerce-loop-product__title\"><a href=\"https:\/\/vetihcr.com\/index.php\/product\/bagger-25l-backpack\/\" class=\"woocommerce-LoopProduct-link-title woocommerce-loop-product__title_ink\">Bagger 25L Backpack<\/a><\/h2><div class=\"product-action-wrap\"><\/div><\/div><\/li>\n<li class=\"entry content-bg loop-entry product type-product post-515 status-publish first instock product_cat-shelters has-post-thumbnail shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/vetihcr.com\/index.php\/product\/515\/\" class=\"woocommerce-loop-image-link woocommerce-LoopProduct-link woocommerce-loop-product__link\"><\/a><div class=\"product-details content-bg entry-content-wrap\"><h2 class=\"woocommerce-loop-product__title\"><a href=\"https:\/\/vetihcr.com\/index.php\/product\/515\/\" class=\"woocommerce-LoopProduct-link-title woocommerce-loop-product__title_ink\">Free Trio Tent<\/a><\/h2><div class=\"product-action-wrap\"><\/div><\/div><\/li>\n<li class=\"entry content-bg loop-entry product type-product post-519 status-publish instock product_cat-shelters has-post-thumbnail shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/vetihcr.com\/index.php\/product\/hexamid-solo-tent\/\" class=\"woocommerce-loop-image-link woocommerce-LoopProduct-link woocommerce-loop-product__link\"><\/a><div class=\"product-details content-bg entry-content-wrap\"><h2 class=\"woocommerce-loop-product__title\"><a href=\"https:\/\/vetihcr.com\/index.php\/product\/hexamid-solo-tent\/\" class=\"woocommerce-LoopProduct-link-title woocommerce-loop-product__title_ink\">Hexamid Solo Tent<\/a><\/h2><div class=\"product-action-wrap\"><\/div><\/div><\/li>\n<li class=\"entry content-bg loop-entry product type-product post-305 status-publish instock product_cat-boots has-post-thumbnail shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/vetihcr.com\/index.php\/product\/mens-hiking-boots\/\" class=\"woocommerce-loop-image-link woocommerce-LoopProduct-link woocommerce-loop-product__link\"><\/a><div class=\"product-details content-bg entry-content-wrap\"><h2 class=\"woocommerce-loop-product__title\"><a href=\"https:\/\/vetihcr.com\/index.php\/product\/mens-hiking-boots\/\" class=\"woocommerce-LoopProduct-link-title woocommerce-loop-product__title_ink\">Men&#8217;s Hiking Boots<\/a><\/h2><div class=\"product-action-wrap\"><\/div><\/div><\/li>\n<li class=\"entry content-bg loop-entry product type-product post-525 status-publish last instock product_cat-backpacks has-post-thumbnail shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/vetihcr.com\/index.php\/product\/midway-12l-pack\/\" class=\"woocommerce-loop-image-link woocommerce-LoopProduct-link woocommerce-loop-product__link\"><\/a><div class=\"product-details content-bg entry-content-wrap\"><h2 class=\"woocommerce-loop-product__title\"><a href=\"https:\/\/vetihcr.com\/index.php\/product\/midway-12l-pack\/\" class=\"woocommerce-LoopProduct-link-title woocommerce-loop-product__title_ink\">Midway 12L Pack<\/a><\/h2><div class=\"product-action-wrap\"><\/div><\/div><\/li>\n<\/ul>\n<\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0b81946 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0b81946\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4463442\" data-id=\"4463442\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a1cfd5 elementor-position-left elementor-view-stacked elementor-shape-circle elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"5a1cfd5\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-box-open\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M425.7 256c-16.9 0-32.8-9-41.4-23.4L320 126l-64.2 106.6c-8.7 14.5-24.6 23.5-41.5 23.5-4.5 0-9-.6-13.3-1.9L64 215v178c0 14.7 10 27.5 24.2 31l216.2 54.1c10.2 2.5 20.9 2.5 31 0L551.8 424c14.2-3.6 24.2-16.4 24.2-31V215l-137 39.1c-4.3 1.3-8.8 1.9-13.3 1.9zm212.6-112.2L586.8 41c-3.1-6.2-9.8-9.8-16.7-8.9L320 64l91.7 152.1c3.8 6.3 11.4 9.3 18.5 7.3l197.9-56.5c9.9-2.9 14.7-13.9 10.2-23.1zM53.2 41L1.7 143.8c-4.6 9.2.3 20.2 10.1 23l197.9 56.5c7.1 2 14.7-1 18.5-7.3L320 64 69.8 32.1c-6.9-.8-13.5 2.7-16.6 8.9z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\tLivraison gratuite d\u00e8s 50\u20ac\t\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0556ca9\" data-id=\"0556ca9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c74626 elementor-position-left elementor-view-stacked elementor-shape-circle elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"5c74626\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-cc-paypal\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M186.3 258.2c0 12.2-9.7 21.5-22 21.5-9.2 0-16-5.2-16-15 0-12.2 9.5-22 21.7-22 9.3 0 16.3 5.7 16.3 15.5zM80.5 209.7h-4.7c-1.5 0-3 1-3.2 2.7l-4.3 26.7 8.2-.3c11 0 19.5-1.5 21.5-14.2 2.3-13.4-6.2-14.9-17.5-14.9zm284 0H360c-1.8 0-3 1-3.2 2.7l-4.2 26.7 8-.3c13 0 22-3 22-18-.1-10.6-9.6-11.1-18.1-11.1zM576 80v352c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V80c0-26.5 21.5-48 48-48h480c26.5 0 48 21.5 48 48zM128.3 215.4c0-21-16.2-28-34.7-28h-40c-2.5 0-5 2-5.2 4.7L32 294.2c-.3 2 1.2 4 3.2 4h19c2.7 0 5.2-2.9 5.5-5.7l4.5-26.6c1-7.2 13.2-4.7 18-4.7 28.6 0 46.1-17 46.1-45.8zm84.2 8.8h-19c-3.8 0-4 5.5-4.2 8.2-5.8-8.5-14.2-10-23.7-10-24.5 0-43.2 21.5-43.2 45.2 0 19.5 12.2 32.2 31.7 32.2 9 0 20.2-4.9 26.5-11.9-.5 1.5-1 4.7-1 6.2 0 2.3 1 4 3.2 4H200c2.7 0 5-2.9 5.5-5.7l10.2-64.3c.3-1.9-1.2-3.9-3.2-3.9zm40.5 97.9l63.7-92.6c.5-.5.5-1 .5-1.7 0-1.7-1.5-3.5-3.2-3.5h-19.2c-1.7 0-3.5 1-4.5 2.5l-26.5 39-11-37.5c-.8-2.2-3-4-5.5-4h-18.7c-1.7 0-3.2 1.8-3.2 3.5 0 1.2 19.5 56.8 21.2 62.1-2.7 3.8-20.5 28.6-20.5 31.6 0 1.8 1.5 3.2 3.2 3.2h19.2c1.8-.1 3.5-1.1 4.5-2.6zm159.3-106.7c0-21-16.2-28-34.7-28h-39.7c-2.7 0-5.2 2-5.5 4.7l-16.2 102c-.2 2 1.3 4 3.2 4h20.5c2 0 3.5-1.5 4-3.2l4.5-29c1-7.2 13.2-4.7 18-4.7 28.4 0 45.9-17 45.9-45.8zm84.2 8.8h-19c-3.8 0-4 5.5-4.3 8.2-5.5-8.5-14-10-23.7-10-24.5 0-43.2 21.5-43.2 45.2 0 19.5 12.2 32.2 31.7 32.2 9.3 0 20.5-4.9 26.5-11.9-.3 1.5-1 4.7-1 6.2 0 2.3 1 4 3.2 4H484c2.7 0 5-2.9 5.5-5.7l10.2-64.3c.3-1.9-1.2-3.9-3.2-3.9zm47.5-33.3c0-2-1.5-3.5-3.2-3.5h-18.5c-1.5 0-3 1.2-3.2 2.7l-16.2 104-.3.5c0 1.8 1.5 3.5 3.5 3.5h16.5c2.5 0 5-2.9 5.2-5.7L544 191.2v-.3zm-90 51.8c-12.2 0-21.7 9.7-21.7 22 0 9.7 7 15 16.2 15 12 0 21.7-9.2 21.7-21.5.1-9.8-6.9-15.5-16.2-15.5z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\tPaiement s\u00e9curis\u00e9\t\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-15934ca\" data-id=\"15934ca\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3cb3506 elementor-position-left elementor-view-stacked elementor-shape-circle elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"3cb3506\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\tConseil au 04 78 32 19 67\t\t\t\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-074b451 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"074b451\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-115c05a\" data-id=\"115c05a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fafaabb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fafaabb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-59d82d1\" data-id=\"59d82d1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e3b40cd elementor-widget elementor-widget-heading\" data-id=\"e3b40cd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Abonnez-vous \u00e0 notre newsletter<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ec83bf2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ec83bf2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f3b8010\" data-id=\"f3b8010\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-214916a elementor-align-right elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"214916a\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">S'abonner<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c31c5bb\" data-id=\"c31c5bb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26f88e8 elementor-align-left elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"26f88e8\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">J'ach\u00e8te<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>V\u00eatements h\u00f4tel, caf\u00e9, restaurant Trouvez sur notre site tous les v\u00eatements et \u00e9quipements n\u00e9cessaires dans les m\u00e9tiers de la restauration et du service. Je d\u00e9couvre Caf\u00e9 Restaurant H\u00f4tel Notre best-seller &#xE934;&#xE934;&#xE934;&#xE934;&#xE934; 5\/5 VESTE DE CUISINE A\u00c9R\u00c9E NOIR &#8211; MANCHE LONGUE &#8211; PORTWEST a veste de cuisine Portwest C838\u00a0utilise un tissu l\u00e9ger et de grands panneaux&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1104,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_kad_post_transparent":"","_kad_post_title":"hide","_kad_post_layout":"fullwidth","_kad_post_sidebar_id":"","_kad_post_content_style":"unboxed","_kad_post_vertical_padding":"hide","_kad_post_feature":"hide","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/vetihcr.com\/index.php\/wp-json\/wp\/v2\/pages\/38"}],"collection":[{"href":"https:\/\/vetihcr.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/vetihcr.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/vetihcr.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vetihcr.com\/index.php\/wp-json\/wp\/v2\/comments?post=38"}],"version-history":[{"count":54,"href":"https:\/\/vetihcr.com\/index.php\/wp-json\/wp\/v2\/pages\/38\/revisions"}],"predecessor-version":[{"id":1316,"href":"https:\/\/vetihcr.com\/index.php\/wp-json\/wp\/v2\/pages\/38\/revisions\/1316"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vetihcr.com\/index.php\/wp-json\/wp\/v2\/media\/1104"}],"wp:attachment":[{"href":"https:\/\/vetihcr.com\/index.php\/wp-json\/wp\/v2\/media?parent=38"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}